{"id":91224,"date":"2023-02-01T08:29:37","date_gmt":"2023-02-01T08:29:37","guid":{"rendered":"https:\/\/www.donnafugata.it\/blog\/il-contributo-di-donnafugata-per-la-protezione-degli-oceani\/"},"modified":"2023-02-03T09:53:18","modified_gmt":"2023-02-03T09:53:18","slug":"unser-beitrag-zum-schutz-der-meere","status":"publish","type":"post","link":"https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/","title":{"rendered":"Unser Beitrag zum Schutz der Meere"},"content":{"rendered":"<p dir=\"ltr\"><strong>Damarino 2022 ist der erste Wein der Welt, der den Nomacorc Ocean-Verschluss verwendet.<\/strong><\/p>\n<p dir=\"ltr\">Ozeane sch\u00fctzen und Plastik zu einer erneuerbaren Ressource machen: Nomacorc Ocean ist der erste Weinverschluss der Welt aus recycelter Plastik aus K\u00fcstengebieten.<\/p>\n<p><span style=\"font-weight: 400\">F\u00fcr die <strong>weltweite Markteinf\u00fchrung<\/strong> hat Vinventions das sizilianische Spitzenweingut <strong>Donnafugata<\/strong> gew\u00e4hlt: Das Familienunternehmen setzt sich seit 30 Jahren f\u00fcr \u00f6kologische und soziale Nachhaltigkeit ein und ist damit idealer Partner f\u00fcr die Pr\u00e4sentation von Nomacorc Ocean.<\/span><\/p>\n<p>Der wei\u00dfe <a href=\"https:\/\/www.donnafugata.it\/de\/produkt\/damarino\/\"><strong>Damarino Bianco Sicilia DOC<\/strong><\/a> ist <strong>der erste Wein der Welt<\/strong>, der <strong>mit einem Korken aus OBP-zertifiziertem Kunststoff<\/strong> verschlossen wird und damit die Verschmutzung der Meere zu verringern hilft. <strong>Ocean Bound Plastic (OBP)<\/strong>\u00a0ist Kunststoffm\u00fcll, der in K\u00fcstengebieten, an Flussl\u00e4ufen und Str\u00e4nden gesammelt wird. Der in K\u00fcstenn\u00e4he hinterlassene M\u00fcll landet mit hoher Wahrscheinlichkeit im Meer, besonders in Regionen, in denen es keine oder nur unzureichende Sammelsysteme gibt.<\/p>\n<p dir=\"ltr\">Mit Nomacorc Ocean, einem Weinverschluss, der zum Schutz der Meeres-\u00d6kosysteme beitr\u00e4gt, geht Vinventions einen weiteren Schritt zum\u00a0<strong>Schutz unseres Planeten,<\/strong> und hin zur Umsetzung der\u00a0<strong>Nachhaltigkeitsziele der Agenda 2030\u00a0der Vereinten Nationen<\/strong>. Weltweit werden viele Ma\u00dfnahmen ergriffen, um die\u00a0<strong>Meeresverschmutzung zu begrenzen<\/strong>, ein Thema, das Anlass zu gro\u00dfer Sorge gibt. Einige dieser Initiativen zielen darauf ab, Abf\u00e4lle zu stoppen und wiederzuverwerten, bevor sie das Meer erreichen: darunter Nomacorc Ocean, der einen Rohstoff aus diesen Abf\u00e4llen verwendet, um diese gem\u00e4\u00df den Prinzipien der\u00a0<strong>Kreislaufwirtschaft<\/strong>\u00a0ein zweites Leben zu geben.<\/p>\n<p>Das Ziel von Vinventions und Donnafugata ist es auch, H\u00e4ndlern und Konsumenten die M\u00f6glichkeit zu geben, durch ihre Entscheidungen zum Schutz der Ozeane beizutragen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Damarino 2022 ist der erste Wein der Welt, der den Nomacorc Ocean-Verschluss verwendet. Ozeane sch\u00fctzen und Plastik zu einer erneuerbaren Ressource machen: Nomacorc Ocean ist der erste Weinverschluss der Welt aus recycelter Plastik aus K\u00fcstengebieten. F\u00fcr die weltweite Markteinf\u00fchrung hat Vinventions das sizilianische Spitzenweingut Donnafugata gew\u00e4hlt: Das Familienunternehmen setzt sich seit 30 Jahren f\u00fcr \u00f6kologische [&hellip;]<\/p>\n","protected":false},"author":255,"featured_media":91050,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2789,2780],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Unser Beitrag zum Schutz der Meere<\/title>\n<meta name=\"description\" content=\"Damarino 2022 ist der erste Wein der Welt, der den Nomacorc Ocean-Verschluss verwendet.Ozeane sch\u00fctzen und Plastik zu einer erneuerbaren Ressource machen: Nomacorc Ocean ist der erste Weinverschluss der Welt aus recycelter Plastik aus K\u00fcstengebieten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unser Beitrag zum Schutz der Meere\" \/>\n<meta property=\"og:description\" content=\"Damarino 2022 ist der erste Wein der Welt, der den Nomacorc Ocean-Verschluss verwendet.Ozeane sch\u00fctzen und Plastik zu einer erneuerbaren Ressource machen: Nomacorc Ocean ist der erste Weinverschluss der Welt aus recycelter Plastik aus K\u00fcstengebieten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/\" \/>\n<meta property=\"og:site_name\" content=\"Donnafugata\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-01T08:29:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-03T09:53:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.donnafugata.it\/wp-content\/uploads\/2023\/01\/DF_ThumbNews-3T1A0302-1080x675-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketingteam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.donnafugata.it\/wp-content\/uploads\/2023\/01\/DF_ThumbNews-3T1A0302-1080x675-1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketingteam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/\",\"url\":\"https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/\",\"name\":\"Unser Beitrag zum Schutz der Meere\",\"isPartOf\":{\"@id\":\"https:\/\/www.donnafugata.it\/en\/#website\"},\"datePublished\":\"2023-02-01T08:29:37+00:00\",\"dateModified\":\"2023-02-03T09:53:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.donnafugata.it\/en\/#\/schema\/person\/52fbab691546ffe746910e752bb682ed\"},\"description\":\"Damarino 2022 ist der erste Wein der Welt, der den Nomacorc Ocean-Verschluss verwendet.Ozeane sch\u00fctzen und Plastik zu einer erneuerbaren Ressource machen: Nomacorc Ocean ist der erste Weinverschluss der Welt aus recycelter Plastik aus K\u00fcstengebieten.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.donnafugata.it\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unser Beitrag zum Schutz der Meere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.donnafugata.it\/en\/#website\",\"url\":\"https:\/\/www.donnafugata.it\/en\/\",\"name\":\"Donnafugata\",\"description\":\"Donnafugata INT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.donnafugata.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.donnafugata.it\/en\/#\/schema\/person\/52fbab691546ffe746910e752bb682ed\",\"name\":\"marketingteam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.donnafugata.it\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8c3207d9378ea88ce0f63bb6e2717ac7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8c3207d9378ea88ce0f63bb6e2717ac7?s=96&d=mm&r=g\",\"caption\":\"marketingteam\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unser Beitrag zum Schutz der Meere","description":"Damarino 2022 ist der erste Wein der Welt, der den Nomacorc Ocean-Verschluss verwendet.Ozeane sch\u00fctzen und Plastik zu einer erneuerbaren Ressource machen: Nomacorc Ocean ist der erste Weinverschluss der Welt aus recycelter Plastik aus K\u00fcstengebieten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Unser Beitrag zum Schutz der Meere","og_description":"Damarino 2022 ist der erste Wein der Welt, der den Nomacorc Ocean-Verschluss verwendet.Ozeane sch\u00fctzen und Plastik zu einer erneuerbaren Ressource machen: Nomacorc Ocean ist der erste Weinverschluss der Welt aus recycelter Plastik aus K\u00fcstengebieten.","og_url":"https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/","og_site_name":"Donnafugata","article_published_time":"2023-02-01T08:29:37+00:00","article_modified_time":"2023-02-03T09:53:18+00:00","og_image":[{"width":1080,"height":675,"url":"https:\/\/www.donnafugata.it\/wp-content\/uploads\/2023\/01\/DF_ThumbNews-3T1A0302-1080x675-1.jpg","type":"image\/jpeg"}],"author":"marketingteam","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.donnafugata.it\/wp-content\/uploads\/2023\/01\/DF_ThumbNews-3T1A0302-1080x675-1.jpg","twitter_misc":{"Verfasst von":"marketingteam","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/","url":"https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/","name":"Unser Beitrag zum Schutz der Meere","isPartOf":{"@id":"https:\/\/www.donnafugata.it\/en\/#website"},"datePublished":"2023-02-01T08:29:37+00:00","dateModified":"2023-02-03T09:53:18+00:00","author":{"@id":"https:\/\/www.donnafugata.it\/en\/#\/schema\/person\/52fbab691546ffe746910e752bb682ed"},"description":"Damarino 2022 ist der erste Wein der Welt, der den Nomacorc Ocean-Verschluss verwendet.Ozeane sch\u00fctzen und Plastik zu einer erneuerbaren Ressource machen: Nomacorc Ocean ist der erste Weinverschluss der Welt aus recycelter Plastik aus K\u00fcstengebieten.","breadcrumb":{"@id":"https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.donnafugata.it\/de\/blog\/unser-beitrag-zum-schutz-der-meere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.donnafugata.it\/de\/"},{"@type":"ListItem","position":2,"name":"Unser Beitrag zum Schutz der Meere"}]},{"@type":"WebSite","@id":"https:\/\/www.donnafugata.it\/en\/#website","url":"https:\/\/www.donnafugata.it\/en\/","name":"Donnafugata","description":"Donnafugata INT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.donnafugata.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.donnafugata.it\/en\/#\/schema\/person\/52fbab691546ffe746910e752bb682ed","name":"marketingteam","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.donnafugata.it\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8c3207d9378ea88ce0f63bb6e2717ac7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3207d9378ea88ce0f63bb6e2717ac7?s=96&d=mm&r=g","caption":"marketingteam"}}]}},"_links":{"self":[{"href":"https:\/\/www.donnafugata.it\/de\/wp-json\/wp\/v2\/posts\/91224"}],"collection":[{"href":"https:\/\/www.donnafugata.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donnafugata.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donnafugata.it\/de\/wp-json\/wp\/v2\/users\/255"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donnafugata.it\/de\/wp-json\/wp\/v2\/comments?post=91224"}],"version-history":[{"count":2,"href":"https:\/\/www.donnafugata.it\/de\/wp-json\/wp\/v2\/posts\/91224\/revisions"}],"predecessor-version":[{"id":91246,"href":"https:\/\/www.donnafugata.it\/de\/wp-json\/wp\/v2\/posts\/91224\/revisions\/91246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donnafugata.it\/de\/wp-json\/wp\/v2\/media\/91050"}],"wp:attachment":[{"href":"https:\/\/www.donnafugata.it\/de\/wp-json\/wp\/v2\/media?parent=91224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donnafugata.it\/de\/wp-json\/wp\/v2\/categories?post=91224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donnafugata.it\/de\/wp-json\/wp\/v2\/tags?post=91224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}